{"id":8,"count":2,"description":"","link":"https:\/\/dev2.alghost.com\/mybestcoaching\/events\/categorie\/webinaire\/","name":"Webinaire","slug":"webinaire","taxonomy":"tribe_events_cat","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dev2.alghost.com\/mybestcoaching\/wp-json\/wp\/v2\/tribe_events_cat\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev2.alghost.com\/mybestcoaching\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/dev2.alghost.com\/mybestcoaching\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/dev2.alghost.com\/mybestcoaching\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=8"},{"href":"https:\/\/dev2.alghost.com\/mybestcoaching\/wp-json\/wp\/v2\/tec_calendar_embed?tribe_events_cat=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}